{"id":3109,"date":"2020-07-31T08:00:16","date_gmt":"2020-07-31T06:00:16","guid":{"rendered":"https:\/\/clusterlogistic.org\/?p=3109"},"modified":"2020-07-19T21:50:30","modified_gmt":"2020-07-19T19:50:30","slug":"sateliot-lanza-nanosatelites-para-dar-conectividad-a-dispositivos-iot-del-sector-logistico","status":"publish","type":"post","link":"https:\/\/clusterlogistic.org\/es\/sateliot-lanza-nanosatelites-para-dar-conectividad-a-dispositivos-iot-del-sector-logistico\/","title":{"rendered":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico"},"content":{"rendered":"<p>La startup espa\u00f1ola\u00a0 \u201cSateliot\u201d enviar\u00e1 en noviembre de este a\u00f1o su primer nanosat\u00e9lite al espacio exterior. Har\u00e1 parte de una constelaci\u00f3n de nanosat\u00e9lites que la empresa dise\u00f1\u00f3 para el funcionamiento del Internet de las Cosas (IoT) con aplicaci\u00f3n al sector log\u00edstico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3113\" src=\"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\" alt=\"\" width=\"1000\" height=\"550\" srcset=\"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg 1000w, https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1-300x165.jpg 300w, https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1-768x422.jpg 768w, https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1-705x388.jpg 705w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>La proyecci\u00f3n de la compa\u00f1\u00eda es lanzar el primer sat\u00e9lite en 2020. Para 2021 contar con el primer sat\u00e9lite 5G del mundo y en 2022 tener la primera constelaci\u00f3n comercial.\u00a0 El objetivo de Sateliot es lograr unir su propia red de constelaci\u00f3n satelital con redes de telecomunicaciones para mejorar la conectividad en el \u00e1rea log\u00edstica.<\/p>\n<p>Los peque\u00f1os aparatos tienen aproximadamente unos 12 kg de peso, orbitar\u00e1n a unos 500 km de la Tierra y s\u00f3lo operar\u00e1n como torres de telefon\u00eda desde el espacio exterior para ofrecer cobertura a todo el territorio. A manera de comparaci\u00f3n los grandes sat\u00e9lites geoestacionarios est\u00e1n a unos 36.000 km del planeta.<\/p>\n<p>La constelaci\u00f3n de baja \u00f3rbita funciona bajo los mismos est\u00e1ndares que las operadoras de telecomunicaciones m\u00f3viles (4G y 5G) como Movistar o China Mobile. Hasta el momento las redes satelitales de IoT funcionaban s\u00f3lo con sus propias redes espaciales. Esta idea es realmente innovadora.<\/p>\n<h2>Aplicaci\u00f3n en la pr\u00e1ctica<\/h2>\n<p>El uso de esta tecnolog\u00eda en los procesos diarios de log\u00edstica permitir\u00e1 por ejemplo, que un cami\u00f3n transportador de mercanc\u00eda utilice una red de operadores m\u00f3viles en espacios delimitados como una ciudad y al salir de ella. Podr\u00e1 conectarse a la constelaci\u00f3n satelital a trav\u00e9s de un roaming.<\/p>\n<p>El transporte de mercanc\u00edas y la log\u00edstica son el sector m\u00e1s abierto al uso de esta tecnolog\u00eda, ya que ve su potencial. Seg\u00fan Sateliot un 26% del Internet de las Cosas se podr\u00e1 aplicar a este mercado.<\/p>\n<p>Con ello la startup pretende volver masiva esta tecnolog\u00eda logrando instalar sensores fuera y dentro de contenedores que permitir\u00e1n recopilar datos durante el recorrido como temperatura, humedad, presencia de humo, niveles de ox\u00edgeno, intentos de ser abierto, etc.<\/p>\n<p>En la actualidad est\u00e1n operando tres grandes constelaciones de sat\u00e9lites que cubren en un porcentaje los requerimientos del IoT empleados por el sector log\u00edstico.\u00a0 Es una soluci\u00f3n disruptiva seg\u00fan los directivos de la compa\u00f1\u00eda que est\u00e1 en v\u00eda de desarrollo la cual busca mezclar las redes m\u00f3viles con su propia red satelital y generar las bases de un nuevo y eficiente modelo de conectividad.<\/p>\n<p>De hecho afirman que un sat\u00e9lite es bueno en cobertura, pero muy malo en capacidad, por ello seg\u00fan Sateliot se hace necesario acceder a redes m\u00f3viles m\u00e1s masivas.<\/p>\n<p>La empresa espera iniciar el a\u00f1o entrante sus primeros proyectos piloto para demostrar a los usuarios la funcionalidad de esta tecnolog\u00eda con miras a empezar a ponerla en operaci\u00f3n a partir de 2022. Para ello est\u00e1n en conversaciones en busca de la firma de convenios con operadores log\u00edsticos internacionales que de llegar a concretarse se dar\u00e1n a conocer oportunamente.<\/p>\n<p>La startup ha venido trabajando en este desarrollo desde 2017 orientando todo su esfuerzo y capacidad en el Internet de las Cosas (IoT), donde a\u00fan hace falta mucha cobertura para satisfacer las necesidades a nivel global.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La startup espa\u00f1ola\u00a0 \u201cSateliot\u201d enviar\u00e1 en noviembre de este a\u00f1o su primer nanosat\u00e9lite al espacio exterior. Har\u00e1 parte de una constelaci\u00f3n de nanosat\u00e9lites que la empresa dise\u00f1\u00f3 para el funcionamiento del Internet de las Cosas (IoT) con aplicaci\u00f3n al sector log\u00edstico. La proyecci\u00f3n de la compa\u00f1\u00eda es lanzar el primer sat\u00e9lite en 2020. Para 2021 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya\" \/>\n<meta property=\"og:description\" content=\"La startup espa\u00f1ola\u00a0 \u201cSateliot\u201d enviar\u00e1 en noviembre de este a\u00f1o su primer nanosat\u00e9lite al espacio exterior. Har\u00e1 parte de una constelaci\u00f3n de nanosat\u00e9lites que la empresa dise\u00f1\u00f3 para el funcionamiento del Internet de las Cosas (IoT) con aplicaci\u00f3n al sector log\u00edstico. La proyecci\u00f3n de la compa\u00f1\u00eda es lanzar el primer sat\u00e9lite en 2020. Para 2021 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00faster Log\u00edstic de Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T06:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00faster Log\u00edstic de Catalunya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00faster Log\u00edstic de Catalunya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/\"},\"author\":{\"name\":\"Cl\u00faster Log\u00edstic de Catalunya\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#\\\/schema\\\/person\\\/2f968404d010f4cfb1fb1faa4cc8cd64\"},\"headline\":\"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico\",\"datePublished\":\"2020-07-31T06:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/\"},\"wordCount\":573,\"publisher\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/\",\"name\":\"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\",\"datePublished\":\"2020-07-31T06:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\",\"contentUrl\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg\",\"width\":1000,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/\",\"name\":\"Cl\u00faster Log\u00edstic de Catalunya\",\"description\":\"associaci\u00f3 sense \u00e0nim de lucre\",\"publisher\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#organization\",\"name\":\"Cl\u00faster Log\u00edstic de Catalunya\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/cropped-Logo-CL-llegenda-gran.jpg\",\"contentUrl\":\"https:\\\/\\\/clusterlogistic.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/cropped-Logo-CL-llegenda-gran.jpg\",\"width\":512,\"height\":512,\"caption\":\"Cl\u00faster Log\u00edstic de Catalunya\"},\"image\":{\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/#\\\/schema\\\/person\\\/2f968404d010f4cfb1fb1faa4cc8cd64\",\"name\":\"Cl\u00faster Log\u00edstic de Catalunya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g\",\"caption\":\"Cl\u00faster Log\u00edstic de Catalunya\"},\"description\":\"Alineem estrat\u00e8gies i sumar esfor\u00e7os per potenciar l'activitat industrial a les pimes | Alineamos estrategias y sumar esfuerzos para potenciar la actividad industrial en las pymes.\",\"url\":\"https:\\\/\\\/clusterlogistic.org\\\/es\\\/author\\\/pilar-minguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/","og_locale":"es_ES","og_type":"article","og_title":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya","og_description":"La startup espa\u00f1ola\u00a0 \u201cSateliot\u201d enviar\u00e1 en noviembre de este a\u00f1o su primer nanosat\u00e9lite al espacio exterior. Har\u00e1 parte de una constelaci\u00f3n de nanosat\u00e9lites que la empresa dise\u00f1\u00f3 para el funcionamiento del Internet de las Cosas (IoT) con aplicaci\u00f3n al sector log\u00edstico. La proyecci\u00f3n de la compa\u00f1\u00eda es lanzar el primer sat\u00e9lite en 2020. Para 2021 [&hellip;]","og_url":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/","og_site_name":"Cl\u00faster Log\u00edstic de Catalunya","article_published_time":"2020-07-31T06:00:16+00:00","og_image":[{"width":1000,"height":550,"url":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg","type":"image\/jpeg"}],"author":"Cl\u00faster Log\u00edstic de Catalunya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00faster Log\u00edstic de Catalunya","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#article","isPartOf":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/"},"author":{"name":"Cl\u00faster Log\u00edstic de Catalunya","@id":"https:\/\/clusterlogistic.org\/es\/#\/schema\/person\/2f968404d010f4cfb1fb1faa4cc8cd64"},"headline":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico","datePublished":"2020-07-31T06:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/"},"wordCount":573,"publisher":{"@id":"https:\/\/clusterlogistic.org\/es\/#organization"},"image":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#primaryimage"},"thumbnailUrl":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg","articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/","url":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/","name":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico - Cl\u00faster Log\u00edstic de Catalunya","isPartOf":{"@id":"https:\/\/clusterlogistic.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#primaryimage"},"image":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#primaryimage"},"thumbnailUrl":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg","datePublished":"2020-07-31T06:00:16+00:00","breadcrumb":{"@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#primaryimage","url":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg","contentUrl":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2020\/07\/Sateliot-lanza-nanosat\u00e9lites-para-dar-conectividad-a-dispositivos-IoT-del-sector-log\u00edstico-1.jpg","width":1000,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/clusterlogistic.org\/sateliot-llanca-nanosatellits-per-donar-connectivitat-a-dispositius-iot-de-el-sector-logistic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clusterlogistic.org\/es\/"},{"@type":"ListItem","position":2,"name":"Sateliot lanza nanosat\u00e9lites para dar conectividad a dispositivos IoT del sector log\u00edstico"}]},{"@type":"WebSite","@id":"https:\/\/clusterlogistic.org\/es\/#website","url":"https:\/\/clusterlogistic.org\/es\/","name":"Cl\u00faster Log\u00edstic de Catalunya","description":"associaci\u00f3 sense \u00e0nim de lucre","publisher":{"@id":"https:\/\/clusterlogistic.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clusterlogistic.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clusterlogistic.org\/es\/#organization","name":"Cl\u00faster Log\u00edstic de Catalunya","url":"https:\/\/clusterlogistic.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clusterlogistic.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2017\/07\/cropped-Logo-CL-llegenda-gran.jpg","contentUrl":"https:\/\/clusterlogistic.org\/wp-content\/uploads\/2017\/07\/cropped-Logo-CL-llegenda-gran.jpg","width":512,"height":512,"caption":"Cl\u00faster Log\u00edstic de Catalunya"},"image":{"@id":"https:\/\/clusterlogistic.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/clusterlogistic.org\/es\/#\/schema\/person\/2f968404d010f4cfb1fb1faa4cc8cd64","name":"Cl\u00faster Log\u00edstic de Catalunya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d70e6dad54fc96678ebb563883ef31c8b8b0a127bb640252f5ba3696ded226fe?s=96&d=mm&r=g","caption":"Cl\u00faster Log\u00edstic de Catalunya"},"description":"Alineem estrat\u00e8gies i sumar esfor\u00e7os per potenciar l'activitat industrial a les pimes | Alineamos estrategias y sumar esfuerzos para potenciar la actividad industrial en las pymes.","url":"https:\/\/clusterlogistic.org\/es\/author\/pilar-minguez\/"}]}},"_links":{"self":[{"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/posts\/3109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/comments?post=3109"}],"version-history":[{"count":2,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/posts\/3109\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/posts\/3109\/revisions\/3117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/media\/3113"}],"wp:attachment":[{"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/media?parent=3109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/categories?post=3109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clusterlogistic.org\/es\/wp-json\/wp\/v2\/tags?post=3109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}